{"id":240,"count":1,"description":"","link":"https:\/\/stagehands.net\/en\/tag\/crew-service\/","name":"Crew service","slug":"crew-service","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crew service Archive - Stagehands.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stagehands.net\/en\/tag\/crew-service\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crew service Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stagehands.net\/en\/tag\/crew-service\/\" \/>\n<meta property=\"og:site_name\" content=\"Stagehands.net\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/stagehands.net\/en\/tag\/crew-service\/\",\"url\":\"https:\/\/stagehands.net\/en\/tag\/crew-service\/\",\"name\":\"Crew service Archive - Stagehands.net\",\"isPartOf\":{\"@id\":\"https:\/\/stagehands.net\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/stagehands.net\/en\/tag\/crew-service\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stagehands.net\/en\/tag\/crew-service\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/stagehands.net\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crew service\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stagehands.net\/en\/#website\",\"url\":\"https:\/\/stagehands.net\/en\/\",\"name\":\"Stagehands.net\",\"description\":\"LOKALE EVENT CREW - WELTWEIT\",\"publisher\":{\"@id\":\"https:\/\/stagehands.net\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stagehands.net\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stagehands.net\/en\/#organization\",\"name\":\"Stagehands\",\"url\":\"https:\/\/stagehands.net\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stagehands.net\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stagehands.net\/wp-content\/uploads\/2020\/09\/Stagehands_klein-e1598948736497.png\",\"contentUrl\":\"https:\/\/stagehands.net\/wp-content\/uploads\/2020\/09\/Stagehands_klein-e1598948736497.png\",\"width\":360,\"height\":86,\"caption\":\"Stagehands\"},\"image\":{\"@id\":\"https:\/\/stagehands.net\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Stagehands.net\",\"https:\/\/www.linkedin.com\/company\/stagehandsworldwide\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Crew service Archive - Stagehands.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stagehands.net\/en\/tag\/crew-service\/","og_locale":"en_US","og_type":"article","og_title":"Crew service Archive","og_url":"https:\/\/stagehands.net\/en\/tag\/crew-service\/","og_site_name":"Stagehands.net","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/stagehands.net\/en\/tag\/crew-service\/","url":"https:\/\/stagehands.net\/en\/tag\/crew-service\/","name":"Crew service Archive - Stagehands.net","isPartOf":{"@id":"https:\/\/stagehands.net\/en\/#website"},"breadcrumb":{"@id":"https:\/\/stagehands.net\/en\/tag\/crew-service\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/stagehands.net\/en\/tag\/crew-service\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/stagehands.net\/en\/"},{"@type":"ListItem","position":2,"name":"Crew service"}]},{"@type":"WebSite","@id":"https:\/\/stagehands.net\/en\/#website","url":"https:\/\/stagehands.net\/en\/","name":"Stagehands.net","description":"LOKALE EVENT CREW - WELTWEIT","publisher":{"@id":"https:\/\/stagehands.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stagehands.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stagehands.net\/en\/#organization","name":"Stagehands","url":"https:\/\/stagehands.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stagehands.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stagehands.net\/wp-content\/uploads\/2020\/09\/Stagehands_klein-e1598948736497.png","contentUrl":"https:\/\/stagehands.net\/wp-content\/uploads\/2020\/09\/Stagehands_klein-e1598948736497.png","width":360,"height":86,"caption":"Stagehands"},"image":{"@id":"https:\/\/stagehands.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Stagehands.net","https:\/\/www.linkedin.com\/company\/stagehandsworldwide"]}]}},"_links":{"self":[{"href":"https:\/\/stagehands.net\/en\/wp-json\/wp\/v2\/tags\/240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stagehands.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/stagehands.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/stagehands.net\/en\/wp-json\/wp\/v2\/posts?tags=240"},{"href":"https:\/\/stagehands.net\/en\/wp-json\/wp\/v2\/tribe_events?tags=240"},{"href":"https:\/\/stagehands.net\/en\/wp-json\/wp\/v2\/portfolio?tags=240"},{"href":"https:\/\/stagehands.net\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}